{"id":286,"date":"2016-12-15T14:23:21","date_gmt":"2016-12-15T13:23:21","guid":{"rendered":"https:\/\/bagesturisme.cat\/restauracio\/restaurant-el-colom\/"},"modified":"2021-02-23T11:10:59","modified_gmt":"2021-02-23T10:10:59","slug":"restaurant-el-colom","status":"publish","type":"restauracio","link":"https:\/\/www.bagesturisme.cat\/es\/restauracio\/restaurant-el-colom\/","title":{"rendered":"Restaurant El Colom"},"content":{"rendered":"Situat al centre de la Vila de Moi\u00e0, \u00e9s un restaurant petit de caire familiar que obria les porten l&#8217;any 1984. El nostre objectiu \u00e9s donar un servei atent dins d\u2019un ambient acollidor i relaxat. Disposem de 50 comensals, dividits en dos espais de 25 persones.<\/p>\n<p>La nostra cuina d&#8217;elaboraci\u00f3 pr\u00f2pia, moderna, per\u00f2 no minimalista, i amb tocs d\u2019autor on tamb\u00e9 es poden trobar els plats de sempre. Una carta que varia al llarg de l\u2019any segons la\u00a0 temporada en la que ens trobem i en la que la seva varietat fa que puguem gaudir des de la millor carn a la llossa, peix salvatge, o d\u2019un arr\u00f2s de llam\u00e0ntol.","protected":false},"author":34,"featured_media":8953,"template":"","class_list":["post-286","restauracio","type-restauracio","status-publish","has-post-thumbnail","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.bagesturisme.cat\/es\/wp-json\/wp\/v2\/restauracio\/286","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.bagesturisme.cat\/es\/wp-json\/wp\/v2\/restauracio"}],"about":[{"href":"https:\/\/www.bagesturisme.cat\/es\/wp-json\/wp\/v2\/types\/restauracio"}],"author":[{"embeddable":true,"href":"https:\/\/www.bagesturisme.cat\/es\/wp-json\/wp\/v2\/users\/34"}],"version-history":[{"count":7,"href":"https:\/\/www.bagesturisme.cat\/es\/wp-json\/wp\/v2\/restauracio\/286\/revisions"}],"predecessor-version":[{"id":8954,"href":"https:\/\/www.bagesturisme.cat\/es\/wp-json\/wp\/v2\/restauracio\/286\/revisions\/8954"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.bagesturisme.cat\/es\/wp-json\/wp\/v2\/media\/8953"}],"wp:attachment":[{"href":"https:\/\/www.bagesturisme.cat\/es\/wp-json\/wp\/v2\/media?parent=286"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}