{"id":13130,"date":"2023-08-21T11:03:37","date_gmt":"2023-08-21T10:03:37","guid":{"rendered":"https:\/\/bagesturisme.cat\/wp-content\/uploads\/2020\/09\/feixes-de-coaner-salo-048.jpg"},"modified":"2023-08-21T11:03:37","modified_gmt":"2023-08-21T10:03:37","slug":"feixes-de-coaner-salo-048","status":"inherit","type":"attachment","link":"https:\/\/www.bagesturisme.cat\/es\/allotjament\/les-feixes-de-coaner\/feixes-de-coaner-salo-048\/","title":{"rendered":"feixes de coaner salo-048"},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"_eb_attr":""},"class_list":["post-13130","attachment","type-attachment","status-inherit","hentry"],"acf":[],"description":{"rendered":"<p class=\"attachment\"><a data-rel=\"iLightbox[postimages]\" data-title=\"\" data-caption=\"\" href='https:\/\/www.bagesturisme.cat\/wp-content\/uploads\/2020\/09\/feixes-de-coaner-salo-048.jpg'><img decoding=\"async\" width=\"601\" height=\"400\" src=\"https:\/\/www.bagesturisme.cat\/wp-content\/uploads\/2020\/09\/feixes-de-coaner-salo-048-601x400.jpg\" class=\"attachment-medium size-medium lazyload\" alt=\"\" srcset=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%272200%27%20height%3D%271464%27%20viewBox%3D%270%200%202200%201464%27%3E%3Crect%20width%3D%272200%27%20height%3D%271464%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-orig-src=\"https:\/\/www.bagesturisme.cat\/wp-content\/uploads\/2020\/09\/feixes-de-coaner-salo-048-601x400.jpg\" data-srcset=\"https:\/\/www.bagesturisme.cat\/wp-content\/uploads\/2020\/09\/feixes-de-coaner-salo-048-601x400.jpg 601w, https:\/\/www.bagesturisme.cat\/wp-content\/uploads\/2020\/09\/feixes-de-coaner-salo-048-768x511.jpg 768w, https:\/\/www.bagesturisme.cat\/wp-content\/uploads\/2020\/09\/feixes-de-coaner-salo-048-1280x852.jpg 1280w, https:\/\/www.bagesturisme.cat\/wp-content\/uploads\/2020\/09\/feixes-de-coaner-salo-048-1536x1022.jpg 1536w\" data-sizes=\"auto\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":2200,"height":1464,"file":"2020\/09\/feixes-de-coaner-salo-048.jpg","filesize":2707603,"sizes":{"medium":{"file":"feixes-de-coaner-salo-048-601x400.jpg","width":601,"height":400,"filesize":72783,"mime_type":"image\/jpeg","source_url":"https:\/\/www.bagesturisme.cat\/wp-content\/uploads\/2020\/09\/feixes-de-coaner-salo-048-601x400.jpg"},"large":{"file":"feixes-de-coaner-salo-048-1280x852.jpg","width":1280,"height":852,"filesize":287532,"mime_type":"image\/jpeg","source_url":"https:\/\/www.bagesturisme.cat\/wp-content\/uploads\/2020\/09\/feixes-de-coaner-salo-048-1280x852.jpg"},"thumbnail":{"file":"feixes-de-coaner-salo-048-150x150.jpg","width":150,"height":150,"filesize":8409,"mime_type":"image\/jpeg","source_url":"https:\/\/www.bagesturisme.cat\/wp-content\/uploads\/2020\/09\/feixes-de-coaner-salo-048-150x150.jpg"},"medium_large":{"file":"feixes-de-coaner-salo-048-768x511.jpg","width":768,"height":511,"filesize":114201,"mime_type":"image\/jpeg","source_url":"https:\/\/www.bagesturisme.cat\/wp-content\/uploads\/2020\/09\/feixes-de-coaner-salo-048-768x511.jpg"},"1536x1536":{"file":"feixes-de-coaner-salo-048-1536x1022.jpg","width":1536,"height":1022,"filesize":394234,"mime_type":"image\/jpeg","source_url":"https:\/\/www.bagesturisme.cat\/wp-content\/uploads\/2020\/09\/feixes-de-coaner-salo-048-1536x1022.jpg"},"2048x2048":{"file":"feixes-de-coaner-salo-048-2048x1363.jpg","width":2048,"height":1363,"filesize":645181,"mime_type":"image\/jpeg","source_url":"https:\/\/www.bagesturisme.cat\/wp-content\/uploads\/2020\/09\/feixes-de-coaner-salo-048-2048x1363.jpg"},"fiat_thumb":{"file":"feixes-de-coaner-salo-048-60x60.jpg","width":60,"height":60,"filesize":2340,"mime_type":"image\/jpeg","source_url":"https:\/\/www.bagesturisme.cat\/wp-content\/uploads\/2020\/09\/feixes-de-coaner-salo-048-60x60.jpg"},"full":{"file":"feixes-de-coaner-salo-048.jpg","width":2200,"height":1464,"mime_type":"image\/jpeg","source_url":"https:\/\/www.bagesturisme.cat\/wp-content\/uploads\/2020\/09\/feixes-de-coaner-salo-048.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"46634308Z CARLES FORTUNY","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"1","keywords":[]}},"post":8429,"source_url":"https:\/\/www.bagesturisme.cat\/wp-content\/uploads\/2020\/09\/feixes-de-coaner-salo-048.jpg","_links":{"self":[{"href":"https:\/\/www.bagesturisme.cat\/es\/wp-json\/wp\/v2\/media\/13130","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.bagesturisme.cat\/es\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/www.bagesturisme.cat\/es\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/www.bagesturisme.cat\/es\/wp-json\/wp\/v2\/users\/3"}],"wp:attached-to":[{"embeddable":true,"post_type":"allotjament","id":8429,"href":"https:\/\/www.bagesturisme.cat\/es\/wp-json\/wp\/v2\/allotjament\/8429"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}