{"id":9201,"date":"2021-03-03T12:20:12","date_gmt":"2021-03-03T11:20:12","guid":{"rendered":"https:\/\/bagesturisme.cat\/wp-content\/uploads\/2016\/12\/Arros-caldos-de-llamantol-restaurant-joncadella.jpg"},"modified":"2021-03-03T12:20:12","modified_gmt":"2021-03-03T11:20:12","slug":"arros-caldos-de-llamantol-restaurant-joncadella","status":"inherit","type":"attachment","link":"https:\/\/www.bagesturisme.cat\/en\/restauracio\/restaurant-joncadella\/arros-caldos-de-llamantol-restaurant-joncadella\/","title":{"rendered":"Arros-caldos-de-llamantol-restaurant-joncadella"},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"_eb_attr":""},"class_list":["post-9201","attachment","type-attachment","status-inherit","hentry"],"acf":[],"description":{"rendered":"<p class=\"attachment\"><a data-rel=\"iLightbox[postimages]\" data-title=\"\" data-caption=\"\" href='https:\/\/www.bagesturisme.cat\/wp-content\/uploads\/2016\/12\/Arros-caldos-de-llamantol-restaurant-joncadella.jpg'><img decoding=\"async\" width=\"400\" height=\"400\" src=\"https:\/\/www.bagesturisme.cat\/wp-content\/uploads\/2016\/12\/Arros-caldos-de-llamantol-restaurant-joncadella.jpg\" class=\"attachment-medium size-medium lazyload\" alt=\"\" srcset=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%27400%27%20height%3D%27400%27%20viewBox%3D%270%200%20400%20400%27%3E%3Crect%20width%3D%27400%27%20height%3D%27400%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-orig-src=\"https:\/\/www.bagesturisme.cat\/wp-content\/uploads\/2016\/12\/Arros-caldos-de-llamantol-restaurant-joncadella.jpg\" data-srcset=\"https:\/\/www.bagesturisme.cat\/wp-content\/uploads\/2016\/12\/Arros-caldos-de-llamantol-restaurant-joncadella-60x60.jpg 60w, https:\/\/www.bagesturisme.cat\/wp-content\/uploads\/2016\/12\/Arros-caldos-de-llamantol-restaurant-joncadella-150x150.jpg 150w, https:\/\/www.bagesturisme.cat\/wp-content\/uploads\/2016\/12\/Arros-caldos-de-llamantol-restaurant-joncadella.jpg 400w\" data-sizes=\"auto\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":400,"height":400,"file":"2016\/12\/Arros-caldos-de-llamantol-restaurant-joncadella.jpg","sizes":{"thumbnail":{"file":"Arros-caldos-de-llamantol-restaurant-joncadella-150x150.jpg","width":150,"height":150,"filesize":4182,"mime_type":"image\/jpeg","source_url":"https:\/\/www.bagesturisme.cat\/wp-content\/uploads\/2016\/12\/Arros-caldos-de-llamantol-restaurant-joncadella-150x150.jpg"},"fiat_thumb":{"file":"Arros-caldos-de-llamantol-restaurant-joncadella-60x60.jpg","width":60,"height":60,"filesize":1211,"mime_type":"image\/jpeg","source_url":"https:\/\/www.bagesturisme.cat\/wp-content\/uploads\/2016\/12\/Arros-caldos-de-llamantol-restaurant-joncadella-60x60.jpg"},"full":{"file":"Arros-caldos-de-llamantol-restaurant-joncadella.jpg","width":400,"height":400,"mime_type":"image\/jpeg","source_url":"https:\/\/www.bagesturisme.cat\/wp-content\/uploads\/2016\/12\/Arros-caldos-de-llamantol-restaurant-joncadella.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]},"filesize":20027},"post":147,"source_url":"https:\/\/www.bagesturisme.cat\/wp-content\/uploads\/2016\/12\/Arros-caldos-de-llamantol-restaurant-joncadella.jpg","_links":{"self":[{"href":"https:\/\/www.bagesturisme.cat\/en\/wp-json\/wp\/v2\/media\/9201","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.bagesturisme.cat\/en\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/www.bagesturisme.cat\/en\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/www.bagesturisme.cat\/en\/wp-json\/wp\/v2\/users\/3"}],"wp:attached-to":[{"embeddable":true,"post_type":"restauracio","id":147,"href":"https:\/\/www.bagesturisme.cat\/en\/wp-json\/wp\/v2\/restauracio\/147"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}