{"id":13528,"date":"2023-10-17T12:23:47","date_gmt":"2023-10-17T11:23:47","guid":{"rendered":"https:\/\/bagesturisme.cat\/wp-content\/uploads\/2018\/12\/corts-de-biosca-055.jpg"},"modified":"2023-10-17T12:27:09","modified_gmt":"2023-10-17T11:27:09","slug":"corts-de-biosca-055","status":"inherit","type":"attachment","link":"https:\/\/www.bagesturisme.cat\/en\/allotjament\/corts-biosca-pcc0023\/corts-de-biosca-055\/","title":{"rendered":"corts de biosca terrassa"},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"_eb_attr":""},"class_list":["post-13528","attachment","type-attachment","status-inherit","hentry"],"acf":[],"description":{"rendered":"<p class=\"attachment\"><a data-rel=\"iLightbox[postimages]\" data-title=\"\" data-caption=\"\" href='https:\/\/www.bagesturisme.cat\/wp-content\/uploads\/2018\/12\/corts-de-biosca-055.jpg'><img decoding=\"async\" width=\"266\" height=\"400\" src=\"https:\/\/www.bagesturisme.cat\/wp-content\/uploads\/2018\/12\/corts-de-biosca-055-266x400.jpg\" class=\"attachment-medium size-medium lazyload\" alt=\"\" srcset=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%271464%27%20height%3D%272200%27%20viewBox%3D%270%200%201464%202200%27%3E%3Crect%20width%3D%271464%27%20height%3D%272200%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-orig-src=\"https:\/\/www.bagesturisme.cat\/wp-content\/uploads\/2018\/12\/corts-de-biosca-055-266x400.jpg\" data-srcset=\"https:\/\/www.bagesturisme.cat\/wp-content\/uploads\/2018\/12\/corts-de-biosca-055-266x400.jpg 266w, https:\/\/www.bagesturisme.cat\/wp-content\/uploads\/2018\/12\/corts-de-biosca-055-681x1024.jpg 681w, https:\/\/www.bagesturisme.cat\/wp-content\/uploads\/2018\/12\/corts-de-biosca-055-768x1154.jpg 768w, https:\/\/www.bagesturisme.cat\/wp-content\/uploads\/2018\/12\/corts-de-biosca-055-1022x1536.jpg 1022w, https:\/\/www.bagesturisme.cat\/wp-content\/uploads\/2018\/12\/corts-de-biosca-055-1363x2048.jpg 1363w, https:\/\/www.bagesturisme.cat\/wp-content\/uploads\/2018\/12\/corts-de-biosca-055.jpg 1464w\" data-sizes=\"auto\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":1464,"height":2200,"file":"2018\/12\/corts-de-biosca-055.jpg","filesize":1926734,"sizes":{"medium":{"file":"corts-de-biosca-055-266x400.jpg","width":266,"height":400,"filesize":41931,"mime_type":"image\/jpeg","source_url":"https:\/\/www.bagesturisme.cat\/wp-content\/uploads\/2018\/12\/corts-de-biosca-055-266x400.jpg"},"large":{"file":"corts-de-biosca-055-681x1024.jpg","width":681,"height":1024,"filesize":191102,"mime_type":"image\/jpeg","source_url":"https:\/\/www.bagesturisme.cat\/wp-content\/uploads\/2018\/12\/corts-de-biosca-055-681x1024.jpg"},"thumbnail":{"file":"corts-de-biosca-055-150x150.jpg","width":150,"height":150,"filesize":11787,"mime_type":"image\/jpeg","source_url":"https:\/\/www.bagesturisme.cat\/wp-content\/uploads\/2018\/12\/corts-de-biosca-055-150x150.jpg"},"medium_large":{"file":"corts-de-biosca-055-768x1154.jpg","width":768,"height":1154,"filesize":229926,"mime_type":"image\/jpeg","source_url":"https:\/\/www.bagesturisme.cat\/wp-content\/uploads\/2018\/12\/corts-de-biosca-055-768x1154.jpg"},"1536x1536":{"file":"corts-de-biosca-055-1022x1536.jpg","width":1022,"height":1536,"filesize":355854,"mime_type":"image\/jpeg","source_url":"https:\/\/www.bagesturisme.cat\/wp-content\/uploads\/2018\/12\/corts-de-biosca-055-1022x1536.jpg"},"2048x2048":{"file":"corts-de-biosca-055-1363x2048.jpg","width":1363,"height":2048,"filesize":550350,"mime_type":"image\/jpeg","source_url":"https:\/\/www.bagesturisme.cat\/wp-content\/uploads\/2018\/12\/corts-de-biosca-055-1363x2048.jpg"},"fiat_thumb":{"file":"corts-de-biosca-055-60x60.jpg","width":60,"height":60,"filesize":2699,"mime_type":"image\/jpeg","source_url":"https:\/\/www.bagesturisme.cat\/wp-content\/uploads\/2018\/12\/corts-de-biosca-055-60x60.jpg"},"full":{"file":"corts-de-biosca-055.jpg","width":1464,"height":2200,"mime_type":"image\/jpeg","source_url":"https:\/\/www.bagesturisme.cat\/wp-content\/uploads\/2018\/12\/corts-de-biosca-055.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"46634308Z CARLES FORTUNY","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"1","keywords":[]}},"post":53,"source_url":"https:\/\/www.bagesturisme.cat\/wp-content\/uploads\/2018\/12\/corts-de-biosca-055.jpg","_links":{"self":[{"href":"https:\/\/www.bagesturisme.cat\/en\/wp-json\/wp\/v2\/media\/13528","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.bagesturisme.cat\/en\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/www.bagesturisme.cat\/en\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/www.bagesturisme.cat\/en\/wp-json\/wp\/v2\/users\/3"}],"wp:attached-to":[{"embeddable":true,"post_type":"allotjament","id":53,"href":"https:\/\/www.bagesturisme.cat\/en\/wp-json\/wp\/v2\/allotjament\/53"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}