{"id":13508,"date":"2023-10-17T12:11:28","date_gmt":"2023-10-17T11:11:28","guid":{"rendered":"https:\/\/bagesturisme.cat\/wp-content\/uploads\/2023\/10\/ViatgeTempsMSB-22.jpg"},"modified":"2023-10-17T12:12:14","modified_gmt":"2023-10-17T11:12:14","slug":"viatgetempsmsb-22","status":"inherit","type":"attachment","link":"https:\/\/www.bagesturisme.cat\/en\/tardor2023\/viatgetempsmsb-22\/","title":{"rendered":"Viatge Temps M\u00f3n Sant Benet"},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"_eb_attr":""},"class_list":["post-13508","attachment","type-attachment","status-inherit","hentry"],"acf":[],"description":{"rendered":"<p class=\"attachment\"><a data-rel=\"iLightbox[postimages]\" data-title=\"\" data-caption=\"\" href='https:\/\/www.bagesturisme.cat\/wp-content\/uploads\/2023\/10\/ViatgeTempsMSB-22-scaled-e1697541156797.jpg'><img decoding=\"async\" width=\"600\" height=\"400\" src=\"https:\/\/www.bagesturisme.cat\/wp-content\/uploads\/2023\/10\/ViatgeTempsMSB-22-600x400.jpg\" class=\"attachment-medium size-medium lazyload\" alt=\"\" srcset=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%271500%27%20height%3D%271000%27%20viewBox%3D%270%200%201500%201000%27%3E%3Crect%20width%3D%271500%27%20height%3D%271000%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-orig-src=\"https:\/\/www.bagesturisme.cat\/wp-content\/uploads\/2023\/10\/ViatgeTempsMSB-22-600x400.jpg\" data-srcset=\"https:\/\/www.bagesturisme.cat\/wp-content\/uploads\/2023\/10\/ViatgeTempsMSB-22-600x400.jpg 600w, https:\/\/www.bagesturisme.cat\/wp-content\/uploads\/2023\/10\/ViatgeTempsMSB-22-768x512.jpg 768w, https:\/\/www.bagesturisme.cat\/wp-content\/uploads\/2023\/10\/ViatgeTempsMSB-22-1280x853.jpg 1280w, https:\/\/www.bagesturisme.cat\/wp-content\/uploads\/2023\/10\/ViatgeTempsMSB-22-scaled-e1697541156797.jpg 1500w, https:\/\/www.bagesturisme.cat\/wp-content\/uploads\/2023\/10\/ViatgeTempsMSB-22-1536x1024.jpg 1536w\" data-sizes=\"auto\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":1500,"height":1000,"file":"2023\/10\/ViatgeTempsMSB-22-scaled-e1697541156797.jpg","filesize":253064,"sizes":{"medium":{"file":"ViatgeTempsMSB-22-600x400.jpg","width":600,"height":400,"filesize":55480,"mime_type":"image\/jpeg","source_url":"https:\/\/www.bagesturisme.cat\/wp-content\/uploads\/2023\/10\/ViatgeTempsMSB-22-600x400.jpg"},"large":{"file":"ViatgeTempsMSB-22-1280x853.jpg","width":1280,"height":853,"filesize":197361,"mime_type":"image\/jpeg","source_url":"https:\/\/www.bagesturisme.cat\/wp-content\/uploads\/2023\/10\/ViatgeTempsMSB-22-1280x853.jpg"},"thumbnail":{"file":"ViatgeTempsMSB-22-150x150.jpg","width":150,"height":150,"filesize":8396,"mime_type":"image\/jpeg","source_url":"https:\/\/www.bagesturisme.cat\/wp-content\/uploads\/2023\/10\/ViatgeTempsMSB-22-150x150.jpg"},"medium_large":{"file":"ViatgeTempsMSB-22-768x512.jpg","width":768,"height":512,"filesize":84018,"mime_type":"image\/jpeg","source_url":"https:\/\/www.bagesturisme.cat\/wp-content\/uploads\/2023\/10\/ViatgeTempsMSB-22-768x512.jpg"},"1536x1536":{"file":"ViatgeTempsMSB-22-1536x1024.jpg","width":1536,"height":1024,"filesize":267420,"mime_type":"image\/jpeg","source_url":"https:\/\/www.bagesturisme.cat\/wp-content\/uploads\/2023\/10\/ViatgeTempsMSB-22-1536x1024.jpg"},"2048x2048":{"file":"ViatgeTempsMSB-22-2048x1365.jpg","width":2048,"height":1365,"filesize":442784,"mime_type":"image\/jpeg","source_url":"https:\/\/www.bagesturisme.cat\/wp-content\/uploads\/2023\/10\/ViatgeTempsMSB-22-2048x1365.jpg"},"fiat_thumb":{"file":"ViatgeTempsMSB-22-60x60.jpg","width":60,"height":60,"filesize":2268,"mime_type":"image\/jpeg","source_url":"https:\/\/www.bagesturisme.cat\/wp-content\/uploads\/2023\/10\/ViatgeTempsMSB-22-60x60.jpg"},"full":{"file":"ViatgeTempsMSB-22-scaled-e1697541156797.jpg","width":1500,"height":1000,"mime_type":"image\/jpeg","source_url":"https:\/\/www.bagesturisme.cat\/wp-content\/uploads\/2023\/10\/ViatgeTempsMSB-22-scaled-e1697541156797.jpg"}},"image_meta":{"aperture":"4","credit":"","camera":"ILCE-7M3","caption":"","created_timestamp":"1695919901","copyright":"","focal_length":"24","iso":"12800","shutter_speed":"0.00625","title":"","orientation":"0","keywords":[]},"original_image":"ViatgeTempsMSB-22.jpg"},"post":13291,"source_url":"https:\/\/www.bagesturisme.cat\/wp-content\/uploads\/2023\/10\/ViatgeTempsMSB-22-scaled-e1697541156797.jpg","_links":{"self":[{"href":"https:\/\/www.bagesturisme.cat\/en\/wp-json\/wp\/v2\/media\/13508","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.bagesturisme.cat\/en\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/www.bagesturisme.cat\/en\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/www.bagesturisme.cat\/en\/wp-json\/wp\/v2\/users\/3"}],"wp:attached-to":[{"embeddable":true,"post_type":"page","id":13291,"href":"https:\/\/www.bagesturisme.cat\/en\/wp-json\/wp\/v2\/pages\/13291"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}