{"id":10084,"date":"2021-06-07T10:58:30","date_gmt":"2021-06-07T09:58:30","guid":{"rendered":"https:\/\/bagesturisme.cat\/wp-content\/uploads\/2016\/12\/suite-domotica-hotel-mas-de-la-sala-6.jpg"},"modified":"2021-06-07T10:58:30","modified_gmt":"2021-06-07T09:58:30","slug":"suite-domotica-hotel-mas-de-la-sala-6","status":"inherit","type":"attachment","link":"https:\/\/www.bagesturisme.cat\/en\/allotjament\/hotel-mas-sala\/suite-domotica-hotel-mas-de-la-sala-6\/","title":{"rendered":"suite dom\u00f2tica hotel mas de la sala 6"},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"_eb_attr":""},"class_list":["post-10084","attachment","type-attachment","status-inherit","hentry"],"acf":[],"description":{"rendered":"<p class=\"attachment\"><a data-rel=\"iLightbox[postimages]\" data-title=\"\" data-caption=\"\" href='https:\/\/www.bagesturisme.cat\/wp-content\/uploads\/2016\/12\/suite-domotica-hotel-mas-de-la-sala-6-scaled.jpg'><img decoding=\"async\" width=\"600\" height=\"400\" src=\"https:\/\/www.bagesturisme.cat\/wp-content\/uploads\/2016\/12\/suite-domotica-hotel-mas-de-la-sala-6-600x400.jpg\" class=\"attachment-medium size-medium lazyload\" alt=\"\" srcset=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%272560%27%20height%3D%271707%27%20viewBox%3D%270%200%202560%201707%27%3E%3Crect%20width%3D%272560%27%20height%3D%271707%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-orig-src=\"https:\/\/www.bagesturisme.cat\/wp-content\/uploads\/2016\/12\/suite-domotica-hotel-mas-de-la-sala-6-600x400.jpg\" data-srcset=\"https:\/\/www.bagesturisme.cat\/wp-content\/uploads\/2016\/12\/suite-domotica-hotel-mas-de-la-sala-6-600x400.jpg 600w, https:\/\/www.bagesturisme.cat\/wp-content\/uploads\/2016\/12\/suite-domotica-hotel-mas-de-la-sala-6-768x512.jpg 768w, https:\/\/www.bagesturisme.cat\/wp-content\/uploads\/2016\/12\/suite-domotica-hotel-mas-de-la-sala-6-1280x853.jpg 1280w, https:\/\/www.bagesturisme.cat\/wp-content\/uploads\/2016\/12\/suite-domotica-hotel-mas-de-la-sala-6-1536x1024.jpg 1536w\" data-sizes=\"auto\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":2560,"height":1707,"file":"2016\/12\/suite-domotica-hotel-mas-de-la-sala-6-scaled.jpg","sizes":{"medium":{"file":"suite-domotica-hotel-mas-de-la-sala-6-600x400.jpg","width":600,"height":400,"filesize":37043,"mime_type":"image\/jpeg","source_url":"https:\/\/www.bagesturisme.cat\/wp-content\/uploads\/2016\/12\/suite-domotica-hotel-mas-de-la-sala-6-600x400.jpg"},"large":{"file":"suite-domotica-hotel-mas-de-la-sala-6-1280x853.jpg","width":1280,"height":853,"filesize":116721,"mime_type":"image\/jpeg","source_url":"https:\/\/www.bagesturisme.cat\/wp-content\/uploads\/2016\/12\/suite-domotica-hotel-mas-de-la-sala-6-1280x853.jpg"},"thumbnail":{"file":"suite-domotica-hotel-mas-de-la-sala-6-150x150.jpg","width":150,"height":150,"filesize":5960,"mime_type":"image\/jpeg","source_url":"https:\/\/www.bagesturisme.cat\/wp-content\/uploads\/2016\/12\/suite-domotica-hotel-mas-de-la-sala-6-150x150.jpg"},"medium_large":{"file":"suite-domotica-hotel-mas-de-la-sala-6-768x512.jpg","width":768,"height":512,"filesize":53758,"mime_type":"image\/jpeg","source_url":"https:\/\/www.bagesturisme.cat\/wp-content\/uploads\/2016\/12\/suite-domotica-hotel-mas-de-la-sala-6-768x512.jpg"},"1536x1536":{"file":"suite-domotica-hotel-mas-de-la-sala-6-1536x1024.jpg","width":1536,"height":1024,"filesize":153533,"mime_type":"image\/jpeg","source_url":"https:\/\/www.bagesturisme.cat\/wp-content\/uploads\/2016\/12\/suite-domotica-hotel-mas-de-la-sala-6-1536x1024.jpg"},"2048x2048":{"file":"suite-domotica-hotel-mas-de-la-sala-6-2048x1366.jpg","width":2048,"height":1366,"filesize":242993,"mime_type":"image\/jpeg","source_url":"https:\/\/www.bagesturisme.cat\/wp-content\/uploads\/2016\/12\/suite-domotica-hotel-mas-de-la-sala-6-2048x1366.jpg"},"fiat_thumb":{"file":"suite-domotica-hotel-mas-de-la-sala-6-60x60.jpg","width":60,"height":60,"filesize":1961,"mime_type":"image\/jpeg","source_url":"https:\/\/www.bagesturisme.cat\/wp-content\/uploads\/2016\/12\/suite-domotica-hotel-mas-de-la-sala-6-60x60.jpg"},"full":{"file":"suite-domotica-hotel-mas-de-la-sala-6-scaled.jpg","width":2560,"height":1707,"mime_type":"image\/jpeg","source_url":"https:\/\/www.bagesturisme.cat\/wp-content\/uploads\/2016\/12\/suite-domotica-hotel-mas-de-la-sala-6-scaled.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]},"original_image":"suite-domotica-hotel-mas-de-la-sala-6.jpg","filesize":355276},"post":42,"source_url":"https:\/\/www.bagesturisme.cat\/wp-content\/uploads\/2016\/12\/suite-domotica-hotel-mas-de-la-sala-6-scaled.jpg","_links":{"self":[{"href":"https:\/\/www.bagesturisme.cat\/en\/wp-json\/wp\/v2\/media\/10084","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.bagesturisme.cat\/en\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/www.bagesturisme.cat\/en\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/www.bagesturisme.cat\/en\/wp-json\/wp\/v2\/users\/3"}],"wp:attached-to":[{"embeddable":true,"post_type":"allotjament","id":42,"href":"https:\/\/www.bagesturisme.cat\/en\/wp-json\/wp\/v2\/allotjament\/42"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}